{"id":2264,"count":5,"description":"","link":"https:\/\/xactskateshop.com\/fr\/categorie-de-produits\/patinage-de-vitesse\/equipement-de-protection-patinage-de-vitesse-courte-piste\/combinaisons-de-patinage-de-vitesse\/","name":"Combinaisons de patinage de vitesse","slug":"combinaisons-de-patinage-de-vitesse","taxonomy":"product_cat","parent":1612,"meta":[],"menu_order":21,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Combinaisons de patinage de vitesse - Xact Skate Shop<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xactskateshop.com\/fr\/categorie-de-produits\/patinage-de-vitesse\/equipement-de-protection-patinage-de-vitesse-courte-piste\/combinaisons-de-patinage-de-vitesse\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Combinaisons de patinage de vitesse - Xact Skate Shop\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xactskateshop.com\/fr\/categorie-de-produits\/patinage-de-vitesse\/equipement-de-protection-patinage-de-vitesse-courte-piste\/combinaisons-de-patinage-de-vitesse\/\" \/>\n<meta property=\"og:site_name\" content=\"Xact Skate Shop\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/xactskateshop.com\\\/fr\\\/categorie-de-produits\\\/patinage-de-vitesse\\\/equipement-de-protection-patinage-de-vitesse-courte-piste\\\/combinaisons-de-patinage-de-vitesse\\\/\",\"url\":\"https:\\\/\\\/xactskateshop.com\\\/fr\\\/categorie-de-produits\\\/patinage-de-vitesse\\\/equipement-de-protection-patinage-de-vitesse-courte-piste\\\/combinaisons-de-patinage-de-vitesse\\\/\",\"name\":\"Combinaisons de patinage de vitesse - Xact Skate Shop\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/xactskateshop.com\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xactskateshop.com\\\/fr\\\/categorie-de-produits\\\/patinage-de-vitesse\\\/equipement-de-protection-patinage-de-vitesse-courte-piste\\\/combinaisons-de-patinage-de-vitesse\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xactskateshop.com\\\/fr\\\/categorie-de-produits\\\/patinage-de-vitesse\\\/equipement-de-protection-patinage-de-vitesse-courte-piste\\\/combinaisons-de-patinage-de-vitesse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/xactskateshop.com\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Patinage de vitesse\",\"item\":\"https:\\\/\\\/xactskateshop.com\\\/fr\\\/categorie-de-produits\\\/patinage-de-vitesse\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00c9quipement de protection patinage de vitesse courte piste\",\"item\":\"https:\\\/\\\/xactskateshop.com\\\/fr\\\/categorie-de-produits\\\/patinage-de-vitesse\\\/equipement-de-protection-patinage-de-vitesse-courte-piste\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Combinaisons de patinage de vitesse\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/xactskateshop.com\\\/fr\\\/#website\",\"url\":\"http:\\\/\\\/xactskateshop.com\\\/fr\\\/\",\"name\":\"Xact Skate Shop\",\"description\":\"Un site utilisant WordPress\",\"publisher\":{\"@id\":\"http:\\\/\\\/xactskateshop.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/xactskateshop.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/xactskateshop.com\\\/fr\\\/#organization\",\"name\":\"XACT Skate Shop\",\"url\":\"http:\\\/\\\/xactskateshop.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\\\/\\\/xactskateshop.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/xactskateshop.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/xactskateshop-dot-com-avec-contour-noir-sans-fond-675x.jpg\",\"contentUrl\":\"http:\\\/\\\/xactskateshop.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/xactskateshop-dot-com-avec-contour-noir-sans-fond-675x.jpg\",\"width\":675,\"height\":247,\"caption\":\"XACT Skate Shop\"},\"image\":{\"@id\":\"http:\\\/\\\/xactskateshop.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/JeanLouiskateshop\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Combinaisons de patinage de vitesse - Xact Skate Shop","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xactskateshop.com\/fr\/categorie-de-produits\/patinage-de-vitesse\/equipement-de-protection-patinage-de-vitesse-courte-piste\/combinaisons-de-patinage-de-vitesse\/","og_locale":"fr_FR","og_type":"article","og_title":"Combinaisons de patinage de vitesse - Xact Skate Shop","og_url":"https:\/\/xactskateshop.com\/fr\/categorie-de-produits\/patinage-de-vitesse\/equipement-de-protection-patinage-de-vitesse-courte-piste\/combinaisons-de-patinage-de-vitesse\/","og_site_name":"Xact Skate Shop","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/xactskateshop.com\/fr\/categorie-de-produits\/patinage-de-vitesse\/equipement-de-protection-patinage-de-vitesse-courte-piste\/combinaisons-de-patinage-de-vitesse\/","url":"https:\/\/xactskateshop.com\/fr\/categorie-de-produits\/patinage-de-vitesse\/equipement-de-protection-patinage-de-vitesse-courte-piste\/combinaisons-de-patinage-de-vitesse\/","name":"Combinaisons de patinage de vitesse - Xact Skate Shop","isPartOf":{"@id":"http:\/\/xactskateshop.com\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/xactskateshop.com\/fr\/categorie-de-produits\/patinage-de-vitesse\/equipement-de-protection-patinage-de-vitesse-courte-piste\/combinaisons-de-patinage-de-vitesse\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/xactskateshop.com\/fr\/categorie-de-produits\/patinage-de-vitesse\/equipement-de-protection-patinage-de-vitesse-courte-piste\/combinaisons-de-patinage-de-vitesse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/xactskateshop.com\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Patinage de vitesse","item":"https:\/\/xactskateshop.com\/fr\/categorie-de-produits\/patinage-de-vitesse\/"},{"@type":"ListItem","position":3,"name":"\u00c9quipement de protection patinage de vitesse courte piste","item":"https:\/\/xactskateshop.com\/fr\/categorie-de-produits\/patinage-de-vitesse\/equipement-de-protection-patinage-de-vitesse-courte-piste\/"},{"@type":"ListItem","position":4,"name":"Combinaisons de patinage de vitesse"}]},{"@type":"WebSite","@id":"http:\/\/xactskateshop.com\/fr\/#website","url":"http:\/\/xactskateshop.com\/fr\/","name":"Xact Skate Shop","description":"Un site utilisant WordPress","publisher":{"@id":"http:\/\/xactskateshop.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/xactskateshop.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"http:\/\/xactskateshop.com\/fr\/#organization","name":"XACT Skate Shop","url":"http:\/\/xactskateshop.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/xactskateshop.com\/fr\/#\/schema\/logo\/image\/","url":"http:\/\/xactskateshop.com\/wp-content\/uploads\/2024\/04\/xactskateshop-dot-com-avec-contour-noir-sans-fond-675x.jpg","contentUrl":"http:\/\/xactskateshop.com\/wp-content\/uploads\/2024\/04\/xactskateshop-dot-com-avec-contour-noir-sans-fond-675x.jpg","width":675,"height":247,"caption":"XACT Skate Shop"},"image":{"@id":"http:\/\/xactskateshop.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/JeanLouiskateshop"]}]}},"_links":{"self":[{"href":"https:\/\/xactskateshop.com\/fr\/wp-json\/wp\/v2\/product_cat\/2264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xactskateshop.com\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/xactskateshop.com\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/xactskateshop.com\/fr\/wp-json\/wp\/v2\/product_cat\/1612"}],"wp:post_type":[{"href":"https:\/\/xactskateshop.com\/fr\/wp-json\/wp\/v2\/product?product_cat=2264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}